{"id":757,"date":"2021-09-09T07:54:45","date_gmt":"2021-09-09T07:54:45","guid":{"rendered":"https:\/\/www.pannapomodoro.com\/?page_id=757"},"modified":"2023-11-01T11:01:04","modified_gmt":"2023-11-01T11:01:04","slug":"pinsa-romana","status":"publish","type":"page","link":"https:\/\/www.pannapomodoro.com\/it\/pinsas\/pinsa-marguerita\/","title":{"rendered":"Pinsa Marguerita"},"content":{"rendered":"<p>La miscela di ingredienti semplici; come acqua, farina, lievito madre e sale, uniti al processo artigianale; Completamente diversa da quella della &#8220;pizza convenzionale&#8221;, permette lo sviluppo di un prodotto di qualit\u00e0 unica, e di facile digestione grazie a diversi fattori caratteristici:<\/p>\n<ul>\n<li>L&#8217;utilizzo del lievito madre, la cui fermentazione 48 ore.<br \/>\nElevata idratazione dell&#8217;impasto; 70%.<br \/>\nUna volta impastato, subisce nuovamente un processo di fermentazione (circa 8 ore)<\/li>\n<\/ul>\n<p>Il risultato, grazie alla miscelazione manuale e all&#8217;alta temperatura che raggiunge il nostro forno in pietra refrattaria; \u00e8 un impasto croccante fuori ma soffice dentro&#8230; facciamo in modo che la caratteristica bolla d&#8217;aria sia presente in ogni porzione della nostra unica \u201cPinsa\u201d.<\/p>\n<p>La fragranza e la consistenza della nostra Pinsa Romana \u00e8 perfettamente conservata e arriva sulla tua tavola come se fosse appena uscita dal nostro forno.<\/p>\n<p>Per tutti questi motivi &#8220;La Pinsa&#8221; \u00e8 un prodotto diverso da tutti gli altri in commercio.<\/p>\n<p>Gli ingredienti sono stati accuratamente selezionati per sfruttare a pieno la qualit\u00e0 e il sapore del nostro lievito madre: Mozzarella e Pomodoro Confit coronano la nostra Pinsa.<\/p>\n<p>Abbiamo curato ogni minimo dettaglio della nostra nuova creazione; innovativo ma con il sapore della tradizione romana; Per questo aggiungiamo nella confezione finale, un contenitore di olio extravergine di oliva toscano aromatizzato al basilico.<\/p>\n<p>Ci auguriamo che vi piaccia tanto quanto noi ci siamo divertiti a crearlo!<\/p>\n<p>E se chiudi gli occhi mentre lo addendi&#8230; sentirai la tradizione dei nostri sapori, che ti trasporter\u00e0 ai piedi del Tevere.<\/p>","protected":false},"excerpt":{"rendered":"La miscela di ingredienti semplici; come acqua, farina, lievito madre e sale, uniti al processo artigianale; Completamente diversa da quella della &#8220;pizza convenzionale&#8221;, permette lo sviluppo di un prodotto di qualit\u00e0 unica, e di facile digestione grazie a diversi fattori caratteristici: L&#8217;utilizzo del lievito madre, la cui fermentazione 48 ore. Elevata idratazione dell&#8217;impasto; 70%. Una&#8230; <a class=\"view-article\" href=\"https:\/\/www.pannapomodoro.com\/it\/pinsas\/pinsa-marguerita\/\">Mostra articolo<\/a>","protected":false},"author":1,"featured_media":1619,"parent":1513,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"product.php","meta":[],"wps_subtitle":"Un prodotto unico nel suo genere.","_links":{"self":[{"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/pages\/757"}],"collection":[{"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":58,"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/pages\/757\/revisions"}],"predecessor-version":[{"id":2132,"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/pages\/757\/revisions\/2132"}],"up":[{"embeddable":true,"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/pages\/1513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/media\/1619"}],"wp:attachment":[{"href":"https:\/\/www.pannapomodoro.com\/it\/wp-json\/wp\/v2\/media?parent=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}